{"id":95047,"date":"2025-12-17T13:45:46","date_gmt":"2025-12-17T16:45:46","guid":{"rendered":"https:\/\/vocesparalelas.com.ar\/sitio\/?p=95047"},"modified":"2025-12-18T21:15:11","modified_gmt":"2025-12-19T00:15:11","slug":"renovacion-de-contratos-en-educacion-de-san-juan-para-el-personal-de-los-departamentos-alejados","status":"publish","type":"post","link":"https:\/\/vocesparalelas.com.ar\/sitio\/renovacion-de-contratos-en-educacion-de-san-juan-para-el-personal-de-los-departamentos-alejados\/","title":{"rendered":"Renovaci\u00f3n de contratos en Educaci\u00f3n de San Juan para el personal de los Departamentos alejados"},"content":{"rendered":"<p>El Ministerio de Educaci\u00f3n del Gobierno de San Juan informa que las personas que poseen Contratos Administrativos de Servicios de Colaboraci\u00f3n que incluye porteros y administrativos residentes en departamentos alejados, deben concurrir al establecimiento indicado en los d\u00edas y horarios que se indican a continuaci\u00f3n.<\/p>\n<ul>\n<li><span style=\"color: #ff6600;\"><strong>Departamento Calingasta: <\/strong><\/span>Viernes. 19 de Diciembre, de 9 a 11,30 en escuela Batalla de Maip\u00fa, Tamber\u00edas, Calingasta.<\/li>\n<li><span style=\"color: #ff6600;\"><strong>Departamento Valle F\u00e9rtil<\/strong>:<\/span> Viernes 19 de diciembre, de 10 a 12,30 en escuela Provincia de Formosa, Mitre y General Acha, Villa San Agust\u00edn.<\/li>\n<li><strong><span style=\"color: #ff6600;\">Departamento J\u00e1chal:<\/span> <\/strong>Lunes 22 de diciembre, de 8,30 a 12,30 en EPET N\u00b01 J\u00e1chal, General Acha y Agust\u00edn G\u00f3mez<\/li>\n<li><strong><span style=\"color: #ff6600;\">Departamento Iglesia: <\/span><\/strong>Lunes 22 de diciembre, de 9 a 10,30 en UGDA Zona L, Santo Domingo s\/n Albergue, Rodeo<\/li>\n<\/ul>\n<p><strong><span style=\"color: #ff6600;\">Documentaci\u00f3n requerida<\/span><\/strong><\/p>\n<ol>\n<li>Dos (2) fotocopias legibles de DNI tarjeta (anverso y reverso), legalizadas.<\/li>\n<li>Constancia de inscripci\u00f3n de ARCA actualizada, donde conste la inscripci\u00f3n en Ingresos Brutos a trav\u00e9s de la leyenda \u201cR\u00e9gimen simplificado impuesto sobre los ingresos brutos San Juan &#8211; AC\u201d. Adem\u00e1s es indispensable tener como actividad principal \u201cSERVICIOS PERSONALES NCP\u201d.<\/li>\n<li>P\u00f3liza por accidentes laborales con vigencia hasta 2026. Seg\u00fan los siguientes importes:<\/li>\n<\/ol>\n<ul>\n<li>Muerte o invalidez total\/parcial por $ 3.000.000<\/li>\n<li>Gastos m\u00e9dicos y farmac\u00e9uticos por $ 150.000<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28629\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2020\/05\/MINISTERIO-EDUCACION-SJ.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2020\/05\/MINISTERIO-EDUCACION-SJ.jpg 800w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2020\/05\/MINISTERIO-EDUCACION-SJ-300x200.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2020\/05\/MINISTERIO-EDUCACION-SJ-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Educaci\u00f3n del Gobierno de San Juan informa que las personas que poseen Contratos Administrativos de Servicios de<\/p>\n","protected":false},"author":3,"featured_media":35176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-95047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-convocatorias"],"acf":[],"_links":{"self":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/95047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=95047"}],"version-history":[{"count":1,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/95047\/revisions"}],"predecessor-version":[{"id":95050,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/95047\/revisions\/95050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media\/35176"}],"wp:attachment":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=95047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=95047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=95047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}