{"id":65460,"date":"2023-11-07T20:02:15","date_gmt":"2023-11-07T23:02:15","guid":{"rendered":"https:\/\/vocesparalelas.com.ar\/sitio\/?p=65460"},"modified":"2023-11-07T20:02:15","modified_gmt":"2023-11-07T23:02:15","slug":"definieron-los-temas-de-la-decima-sesion-del-periodo-ordinario-en-labor-parlamentaria-de-san-juan","status":"publish","type":"post","link":"https:\/\/vocesparalelas.com.ar\/sitio\/definieron-los-temas-de-la-decima-sesion-del-periodo-ordinario-en-labor-parlamentaria-de-san-juan\/","title":{"rendered":"Definieron los temas de la D\u00e9cima Sesi\u00f3n del Per\u00edodo Ordinario en Labor Parlamentaria de San Juan"},"content":{"rendered":"<div class=\"itemFullText jbintrotext\">\n<p>El Martes, 7 de Noviembre de 2023, los diputados titulares de los diferentes bloques que forman parte de la Legislatura se reunieron con el vicegobernador CPN Roberto Gattoni para conformar el temario del orden del d\u00eda de la D\u00e9cima Sesi\u00f3n del Per\u00edodo Ordinario, a realizarse el Jueves, 9 de Noviembre.<\/p>\n<\/div>\n<div class=\"itemFullText\">\n<p>El encuentro fue cumplido en la sala de Situaci\u00f3n del cuarto piso del edificio Anexo de la Legislatura. Estuvo presente el vicepresidente primero, diputado Eduardo Cabello; el vicepresidente segundo, diputado Carlos Platero; el vicepresidente alterno, legislador Dr. Edgardo Sancassani; el secretario Legislativo Dr. Nicol\u00e1s Alvo; y los presidentes de los bloques Justicialista, legislador Juan Carlos Abarca; Producci\u00f3n y Trabajo, diputado Sergio Miodowsky; Bloquista, legislador Prof. Andr\u00e9s Chanampa; Frente Grande, diputado Arq. Horacio Quiroga; Del Este, legislador Marcelo Mallea; Lealtad Justicialista, diputado Lic. Leonardo Gioja; San Juan Primero, Enrique Monta\u00f1o; ConFe Somos San Juan, diputada Dra. Florencia Pe\u00f1aloza; Actuar, Gustavo Us\u00edn; y PRO Juntos por el Cambio, Enzo Cornejo.<\/p>\n<p>Los asuntos que obtuvieron despacho favorable en las respectivas comisiones y que eventualmente podr\u00edan ser abordados en la sesi\u00f3n son los siguientes:<\/p>\n<p><span style=\"color: #800080;\"><strong>Declaraciones como bienes integrantes del Patrimonio Cultural<\/strong><\/span><\/p>\n<p>En primer lugar, la Legislatura deber\u00e1 definir si otorga acuerdo a un proyecto de Ley del Poder Ejecutivo, mediante mensaje N\u00ba 64, por el cual se declara Bien integrante del Patrimonio Cultural de la Provincia, dentro de los alcances de la Ley Provincial N\u00b0 571-F al &#8216;Museo Provincial de Bellas Artes Franklin Rawson- Ex Casino Provincial\u00bb ubicado en Avenida Libertador General San Martin 902, Oeste, Capital, provincia de San Juan design\u00e1ndolo como Monumento Hist\u00f3rico y Art\u00edstico en los t\u00e9rminos del art\u00edculo 4\u00b0, inciso A) apartado 2.<\/p>\n<p>Asimismo, abordar\u00e1 el proyecto de Ley tambi\u00e9n del Ejecutivo, mediante mensaje N\u00ba 67, por el que se declara bien integrante del Patrimonio Cultural de la provincia al Banco de Gemoplasma Nacional de Olivo ubicada en las calles Sarmiento y San Juan del departamento San Mart\u00edn de la provincia de San Juan, design\u00e1ndolo como \u00abPatrimonio Cient\u00edfico\u00bb en los t\u00e9rminos del del art\u00edculo 4\u00b0, inciso \u00abC\u00bb apartado 5 de la mencionada Ley.<\/p>\n<p>Por otra parte, el cuerpo tratar\u00e1 un proyecto de Ley remitido por el Poder Ejecutivo, mediante mensaje N\u00ba 68, que propone declarar Bien integrante del Patrimonio Cultural de la Provincia, a la tumba donde yace Don Eusebio de Jes\u00fas Dojorti \u00abBuenaventura Luna\u00bb ubicada en el cementerio de la localidad de Huaco (sobre la Ruta Nacional N\u00b0 40 que a su vez conecta con la Ruta Provincial N\u00b0 150), departamento J\u00e1chal, design\u00e1ndolo como \u00abSolar Hist\u00f3rico\u00bb en los t\u00e9rminos del art\u00edculo 4\u00b0, inciso \u00abB\u00bb apartado 2.<\/p>\n<p>Y, por \u00faltimo, la C\u00e1mara someter\u00e1 a votaci\u00f3n un proyecto de Ley presentado por el diputado Rub\u00e9n Carri\u00f3n que propone declarar al edificio Legislativo como Monumento Hist\u00f3rico Provincial a fin de que el mismo sea parte del Patrimonio Cultural y Natural de la Provincia, conforme a la definici\u00f3n y caracteres previstos por la Ley N\u00b0 57I-F en su art\u00edculo 4) inciso A) apartado 1).<\/p>\n<p><span style=\"color: #800080;\"><strong>Donaci\u00f3n de inmueble para la Asociaci\u00f3n Civil Club Atl\u00e9tico Minero<\/strong><\/span><\/p>\n<p class=\"Default\">En la ocasi\u00f3n, los legisladores tratar\u00e1n un proyecto de Ley remitido por el Poder Ejecutivo, mediante mensaje N\u00ba 85, el cual dispone la donaci\u00f3n de un inmueble, ubicado en calle Roque S\u00e1enz Pe\u00f1a s\/n, departamento Santa Luc\u00eda, perteneciente al dominio privado del Estado Provincial a favor de la entidad denominada \u00abAsociaci\u00f3n Civil Club Atl\u00e9tico Minero\u00bb.<\/p>\n<p class=\"Default\">El objeto de este asunto consiste en permitir a la entidad donataria la construcci\u00f3n de su sede social.<\/p>\n<p class=\"Default\"><span style=\"color: #800080;\"><strong>Incorporaci\u00f3n de nuevos tipos penales al Sistema Acusatorio<\/strong><\/span><\/p>\n<p>Luego, el cuerpo parlamentario abordar\u00e1 la modificaci\u00f3n de la Ley 1851-O, C\u00f3digo Procesal Penal, para incorporar a la normativa la investigaci\u00f3n y juzgamiento de la totalidad de los delitos inform\u00e1ticos y dem\u00e1s delitos tipificados por Ley Nacional N\u00b0 26388.<\/p>\n<p>De esta manera, el texto quedar\u00e1 redactado de la siguiente forma:<\/p>\n<p class=\"Default\">\u00a0<strong>\u201cART\u00cdCULO 1.-\u00a0<\/strong>Se incorpora al \u00e1mbito de aplicaci\u00f3n del C\u00f3digo Procesal Penal Ley 1851 \u20140, la investigaci\u00f3n y juzgamiento de la totalidad de los Delitos Inform\u00e1ticos y dem\u00e1s tipificados en la Ley 26.388.<\/p>\n<p class=\"Default\"><strong>ART\u00cdCULO 2.-\u00a0<\/strong>A los efectos del cumplimiento de lo establecido en esta ley, se crean los siguientes cargos:<\/p>\n<p class=\"Default\">Dos (2) cargos de Agente Fiscal cuyos titulares ser\u00e1n designados como Fiscal de Primera Instancia.<\/p>\n<p class=\"Default\">Un (1) cargo de Defensor Oficial. Las respectivas designaciones de los miembros del Ministerio P\u00fablico ser\u00e1n formalizadas a requerimiento de la Corte de Justicia por pedido del Fiscal General de la Corte.<\/p>\n<p class=\"Default\"><strong>ART\u00cdCULO 3.-\u00a0<\/strong>Comun\u00edquese al Poder Ejecutivo.\u201d<\/p>\n<p class=\"Default\"><span style=\"color: #800080;\"><strong>Modificaci\u00f3n del Sistema Procesal Penal de la Provincia<\/strong><\/span><\/p>\n<p class=\"Default\">Tambi\u00e9n, la Legislatura deber\u00e1 tratar la modificaci\u00f3n de la Ley N\u00b0 1993-O, Sistema Procesal Penal de la provincia de San Juan, impulsada por la Corte de Justicia, la cual propone lo siguiente:<\/p>\n<p class=\"Default\">\u00a0<strong>ART\u00cdCULO 1.-\u00a0<\/strong>Se sustituye el art\u00edculo 10 de la ley N\u00b0 1993-0, el que quedar\u00e1 redactado de la siguiente manera:<\/p>\n<p class=\"Default\">\u00a0<strong>ARTICULO 10:\u00a0<\/strong>Competencia del Colegio de Jueces: Los Magistrados que componen el Colegio de Jueces de la Primera Circunscripci\u00f3n. Judicial tienen la competencia que les confieren los Art\u00edculos 68, 71 y 72 de la Ley 1851-0, y las que resultan inherentes conforme las facultades que dicha ley les atribuye.<\/p>\n<p class=\"Default\">\u00a0El Colegio de Jueces de la Segunda Circunscripci\u00f3n Judicial posee id\u00e9ntica competencia, salvo la inherente al juzgamiento de los delitos dolosos, cuando el fiscal, en oportunidad de formular el requerimiento acusatorio, pretende una pena privativa de libertad de m\u00e1s de diez (10) a\u00f1os, en cuyo supuesto intervendr\u00e1 el Colegio de Jueces de la Primera Circunscripci\u00f3n.<\/p>\n<p class=\"Default\">Los Magistrados que componen el Colegio de Jueces de la Segunda Circunscripci\u00f3n Judicial tienen la competencia que establece el art\u00edculo 73 de la Ley 1851-0. Asimismo, son competentes para entender en la aplicaci\u00f3n del procedimiento de Juicio Abreviado previsto en el Art. 413, ss y cc. de la LP 1851- O, siempre que el acuerdo sobre la pena no supere los diez (10) a\u00f1os de prisi\u00f3n. En tal caso, la competencia corresponde al Colegio de Jueces de la Primera Circunscripci\u00f3n Judicial.<\/p>\n<p class=\"Default\">\u00a0\u00a0<strong>ART\u00cdCULO 2.-\u00a0<\/strong>Comun\u00edquese al Poder Ejecutivo<\/p>\n<p class=\"Default\"><span style=\"color: #800080;\"><strong>Modificaci\u00f3n del C\u00f3digo de Faltas de la provincia<\/strong><\/span><\/p>\n<p class=\"Default\">Despu\u00e9s, la C\u00e1mara someter\u00e1 a votaci\u00f3n un proyecto de Ley presentado por el diputado Edgardo Sancassani, el cual establece la modificaci\u00f3n del art\u00edculo 19\u00ba de la Ley 941-R &#8211; C\u00f3digo de Faltas de la provincia de San Juan, el que quedar\u00e1 redactado de la siguiente manera:<\/p>\n<p class=\"Default\"><strong>ART\u00cdCULO 19\u00b0.- MULTA. JUS.\u00a0<\/strong>La pena de multa obligar\u00e1 al contraventor a pagar una suma\u00a0de dinero.\u00a0La unidad para determinar la cuant\u00eda de la multa es el Jus (1J) equivale a veinte unidades\u00a0tributarias (20 U.T.). En las infracciones que no se fijaren un m\u00ednimo, este nunca ser\u00e1 inferior\u00a0a diez Jus (10 J). El valor actualizado de la Unidad Tributaria (U.T.) es de exhibici\u00f3n obligatoria en la sede de cada Juzgado.<\/p>\n<p class=\"Default\"><span style=\"color: #800080;\"><strong>Adhesi\u00f3n a la Ley Nacional denominada Lucio Dupuy<\/strong><\/span><\/p>\n<p class=\"Default\">Por otra parte, la Legislatura pondr\u00e1 a consideraci\u00f3n un proyecto de Ley de autor\u00eda de la diputada Fernanda Paredes, el cual tiene por objeto la adhesi\u00f3n de la Provincia de San Juan a la ley Nacional denominada \u00abLucio Dupuy\u00bb, por la cual se crean una serie de mecanismos y herramientas para la protecci\u00f3n de los Derechos de la Infancia y Prevenci\u00f3n Contra las Violencias de los Ni\u00f1os, Ni\u00f1as y Adolescentes.<\/p>\n<p class=\"Default\"><span style=\"color: #800080;\"><strong>Renuncias a cargos en el Tribunal de Cuentas<\/strong><\/span><\/p>\n<p>El cuerpo Legislativo considerar\u00e1, por un lado, la nota de la vicepresidente del Tribunal de Cuentas, Graciela Ester Chaves, a trav\u00e9s de la cual pone en conocimiento la renuncia al cargo que detenta, condicionada al otorgamiento de la jubilaci\u00f3n cuando culmine el procedimiento correspondiente.<\/p>\n<p>Por otro lado, abordar\u00e1 la nota del vocal del Tribunal de Cuentas de la provincia, V\u00edctor Aldo Molina, por la cual tambi\u00e9n presenta su renuncia al cargo que ejerce y con el que fuera honrado a partir de la designaci\u00f3n efectuada por Resoluci\u00f3n No 085\/2012 de la C\u00e1mara de Diputados y Decreto No 0946\/2012 del Poder Ejecutivo Provincial.<\/p>\n<p><span style=\"color: #800080;\"><strong>Proyectos de Resoluci\u00f3n<\/strong><\/span><\/p>\n<p>En la oportunidad, el cuerpo legislativo abordar\u00e1 los siguientes proyectos de Resoluci\u00f3n que proponen declarar de inter\u00e9s:<\/p>\n<ul>\n<li>Art\u00edstico, cultural, social, tur\u00edstico y educativo al \u00abFestival de Tango San Juan\u00bb, que tendr\u00e1 lugar en nuestra provincia del 07 al 11 de diciembre de 2023. (Diputada Celina Ramella)<\/li>\n<li>Las Jornadas del II Congreso Provincial de Seguridad e Higiene en el Trabajo. (Diputado Gustavo Us\u00edn)<\/li>\n<\/ul>\n<p><span style=\"color: #800080;\"><strong>Proyectos que ingresar\u00e1n a comisiones<\/strong><\/span><\/p>\n<p>En la D\u00e9cima Sesi\u00f3n, ingresar\u00e1n a comisiones para su an\u00e1lisis y estudio los siguientes proyectos:<\/p>\n<ul>\n<li>Proyecto de Ley presentado por el Poder Ejecutivo, mediante mensaje N\u00b0 92, por el que se aprueba la Resoluci\u00f3n N\u00b0 291-IPEEM-2023.<\/li>\n<li>Proyecto de Ley presentado por el Poder Ejecutivo, mediante mensaje N\u00b0 93, por el que se aprueba la Resoluci\u00f3n N\u00b0 302-IPEEM-2023.<\/li>\n<li>Comunicaci\u00f3n Oficial presentada por la Subdirectora del Departamento de Ciencias Jur\u00eddicas de la Facultad de Ciencias Sociales de la Universidad de San Juan.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44361\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2021\/11\/ANEXO-07.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2021\/11\/ANEXO-07.jpg 800w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2021\/11\/ANEXO-07-300x200.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2021\/11\/ANEXO-07-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<\/div>\n<div class=\"clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Martes, 7 de Noviembre de 2023, los diputados titulares de los diferentes bloques que forman parte de la Legislatura<\/p>\n","protected":false},"author":3,"featured_media":65463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-65460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"acf":[],"_links":{"self":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/65460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=65460"}],"version-history":[{"count":1,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/65460\/revisions"}],"predecessor-version":[{"id":65464,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/65460\/revisions\/65464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media\/65463"}],"wp:attachment":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=65460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=65460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=65460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}