{"id":64908,"date":"2023-10-24T21:18:09","date_gmt":"2023-10-25T00:18:09","guid":{"rendered":"https:\/\/vocesparalelas.com.ar\/sitio\/?p=64908"},"modified":"2023-10-27T01:22:46","modified_gmt":"2023-10-27T04:22:46","slug":"premiados-en-la-semana-de-juventudes-en-san-juan","status":"publish","type":"post","link":"https:\/\/vocesparalelas.com.ar\/sitio\/premiados-en-la-semana-de-juventudes-en-san-juan\/","title":{"rendered":"Premiados en la Semana de Juventudes en San Juan"},"content":{"rendered":"<p>La Semana de Juventudes es el evento que el Gobierno de San Juan estableci\u00f3 en la agenda anual para celebrar y empoderar a este sector etario, a trav\u00e9s de una serie de diferentes actividades en m\u00faltiples espacios de la provincia.<\/p>\n<p>Precisamente, una de las premisas de esta acci\u00f3n p\u00fablica, surgida desde el Ministerio de Desarrollo Humano y Promoci\u00f3n Social es la realizaci\u00f3n de diversas competencias en tem\u00e1ticas referidas al arte, deporte y cultura, buscando alentar la participaci\u00f3n activa.<\/p>\n<p>En esta oportunidad, la Direcci\u00f3n de Juventudes apost\u00f3 nuevamente por una serie de espacios para que j\u00f3venes de todos los departamentos puedan ser protagonistas, mostrar sus talentos y al mismo tiempo, divertirse.<\/p>\n<p>En ese sentido, se llev\u00f3 adelante la entrega de premios correspondientes a cada ganador y ganadora de las competencias. Al respecto, el ministro Fabian Aballay expres\u00f3 \u201cnosotros creemos que hoy es el momento en que el Gobierno debe interactuar con los j\u00f3venes y as\u00ed lo hicimos durante estos cuatro a\u00f1os. Podemos hablar de una serie de acciones, como por ejemplo, las becas de transporte o el programa Joven Pod\u00e9s como herramientas de inclusi\u00f3n y desarrollo, pero adem\u00e1s, tambi\u00e9n se busc\u00f3 crear espacios de expresi\u00f3n para que cada joven pueda desarrollar su talento, entendiendo que hoy son actores protag\u00f3nicos en el desarrollo de una gran provincia, como es nuestra querida provincia de San Juan\u201d.<\/p>\n<p>Por su parte, el subsecretario de Protecci\u00f3n, Promoci\u00f3n y Desarrollo Social, Marcos Andino, agreg\u00f3 \u201cen esta gesti\u00f3n por decisi\u00f3n del ministro, el gobernador U\u00f1ac, pero sobre todo por Emiliano Paradiso y por su equipo de trabajo, pudieron realizar estas jornadas que son muy importantes, donde pudimos visibilizar los talentos, los valores que tienen nuestros j\u00f3venes.<\/p>\n<p>Por \u00faltimo, el director de Juventudes, Emiliano Paradiso dijo \u201cdurante esta gesti\u00f3n buscamos que los j\u00f3venes no solo participaran como espectadores de su fiesta sino tambi\u00e9n, como protagonistas. Estamos poniendo en valor el esfuerzo de cada uno de ustedes y como nos pide el gobernador, poder mostrar a la sociedad la calidad de j\u00f3venes que tenemos\u201d.<\/p>\n<ul>\n<li><span style=\"color: #ff0000;\"><strong>Baila San Juan: Individual:<\/strong><\/span> 1\u00b0 Marisol Pinilla 2\u00b0 Mar\u00eda Paz Gonz\u00e1lez,\u00a0<strong><span style=\"color: #ff0000;\">Duo:<\/span><\/strong> 1\u00b0 Wally y Jimy 2\u00b0 Juan Ignacio L\u00f3pez,\u00a0<strong><span style=\"color: #ff0000;\">Grupos:<\/span><\/strong> 1\u00b0 Nemesis Crew 2\u00b0 Shadows<\/li>\n<li><strong><span style=\"color: #ff0000;\">Ajedrez:\u00a0<\/span><\/strong>1\u00b0 Gabriel Pereyra,\u00a02\u00b0 Gabriel Illanes,\u00a03\u00b0 Agust\u00edn Ferrero<\/li>\n<li><strong><span style=\"color: #ff0000;\">Truco:\u00a0<\/span><\/strong>1\u00b0 Milena Casemiro,\u00a02\u00b0 Kevin Narv\u00e1ez,\u00a03\u00b0 Matias Lorenzo<\/li>\n<li><strong><span style=\"color: #ff0000;\">Dise\u00f1art:\u00a0<\/span><\/strong>1\u00b0 Nicol\u00e1s Arroyo,\u00a02\u00b0 Delfina Bastante,\u00a03\u00b0 Erica Camacho<\/li>\n<li><strong><span style=\"color: #ff0000;\">Escritura:\u00a0<\/span><\/strong>1\u00b0 Camila Rey,\u00a02\u00b0 Victoria Saenz,\u00a03\u00b0 Tob\u00edas Chavez<\/li>\n<li><strong><span style=\"color: #ff0000;\">Somos M\u00fasica:\u00a0<\/span><\/strong>1\u00b0 Lucas Sastriques,\u00a02\u00b0 Jonatan Gil,\u00a03\u00b0 Lucho Band,\u00a04\u00b0 Vainilla,\u00a03\u00b0 Ernesto G\u00f3mez<\/li>\n<li><strong><span style=\"color: #ff0000;\">Fotograf\u00eda:\u00a0<\/span><\/strong>1\u00b0 Yasmel Pizarro,\u00a02\u00b0 Bruno Simonelli,\u00a03\u00b0 Ana Laura Gutierrez<\/li>\n<li><strong><span style=\"color: #ff0000;\">F\u00fatbol Femenino:\u00a0<\/span><\/strong>1\u00b0 Las morochas del Este, 2\u00b0 Las verdinegras<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Semana de Juventudes es el evento que el Gobierno de San Juan estableci\u00f3 en la agenda anual para celebrar<\/p>\n","protected":false},"author":3,"featured_media":64911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[8],"tags":[],"class_list":["post-64908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos"],"acf":[],"_links":{"self":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/64908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=64908"}],"version-history":[{"count":1,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/64908\/revisions"}],"predecessor-version":[{"id":64912,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/64908\/revisions\/64912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media\/64911"}],"wp:attachment":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=64908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=64908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=64908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}