{"id":61781,"date":"2023-07-31T20:10:27","date_gmt":"2023-07-31T23:10:27","guid":{"rendered":"https:\/\/vocesparalelas.com.ar\/sitio\/?p=61781"},"modified":"2023-07-31T20:27:23","modified_gmt":"2023-07-31T23:27:23","slug":"encuentro-de-la-orquesta-infantil-argentina-con-5-musicos-de-san-juan","status":"publish","type":"post","link":"https:\/\/vocesparalelas.com.ar\/sitio\/encuentro-de-la-orquesta-infantil-argentina-con-5-musicos-de-san-juan\/","title":{"rendered":"Encuentro de la Orquesta Infantil Argentina con 5 m\u00fasicos de San Juan"},"content":{"rendered":"<p>La Sociedad de Orquestas Infantiles y Juveniles de Argentina &#8211; SOIJAr &#8211; realiza el \u00abEncuentro de la Orquesta Infantil Argentina\u00bb &#8211; OIA -, un evento musical extraordinario que cuenta con la participaci\u00f3n destacada de cinco talentosos alumnos de la Orquesta Escuela de San Juan.<\/p>\n<p>Tras el exitoso \u00abFestival 2023\u00bb, los Maestros responsables han confeccionado una lista de orden de m\u00e9rito para conformar la OIA, y entre los seleccionados se encuentran<\/p>\n<ul>\n<li>Ramiro Tejada,<\/li>\n<li>Rodrigo S\u00e1nchez,<\/li>\n<li>Emilia Rodr\u00edguez,<\/li>\n<li>Martina Rodr\u00edguez y<\/li>\n<li>Santiago Mijares<\/li>\n<\/ul>\n<p>Ellos provenientes de la Orquesta Escuela de San Juan y han demostrado un excepcional talento y dedicaci\u00f3n en su formaci\u00f3n musical, y ahora tendr\u00e1n la oportunidad de integrar la prestigiosa Orquesta Infantil Argentina.<\/p>\n<p>El evento se desarrolla en el predio del Centro Recreativo Nacional Bosques de Ezeiza &#8211; Ce.Re.Na &#8211; desde el 31 de Julio hasta el 4 de Agosto de 2023.<\/p>\n<p>Durante esos d\u00edas, los alumnos de la Orquesta Escuela de San Juan se unen a otros j\u00f3venes m\u00fasicos de diferentes partes del pa\u00eds para ensayar y prepararse para el gran concierto final en Tecn\u00f3polis, el Viernes, 4 de Agosto, a las 16 hs.<\/p>\n<p>El repertorio seleccionado para la ocasi\u00f3n es emocionante y desafiante, incluyendo el<\/p>\n<ul>\n<li>Primer y Cuarto Movimiento de la Sinfon\u00eda N\u00b0 5 de Beethoven<\/li>\n<li>Movimientos Primavera e Invierno de Vivaldi, con los solistas Josefina Mart\u00ed y Vicente Rodr\u00edguez.<\/li>\n<\/ul>\n<p>La incorporaci\u00f3n de estos cinco j\u00f3venes m\u00fasicos de San Juan en la Orquesta Infantil Argentina es un motivo de orgullo para la Orquesta Escuela y una oportunidad \u00fanica para que los talentos locales puedan compartir escenario con otros j\u00f3venes apasionados de la m\u00fasica de Argentina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sociedad de Orquestas Infantiles y Juveniles de Argentina &#8211; SOIJAr &#8211; realiza el \u00abEncuentro de la Orquesta Infantil Argentina\u00bb<\/p>\n","protected":false},"author":3,"featured_media":42245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-61781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"acf":[],"_links":{"self":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/61781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=61781"}],"version-history":[{"count":1,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/61781\/revisions"}],"predecessor-version":[{"id":61784,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/61781\/revisions\/61784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media\/42245"}],"wp:attachment":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=61781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=61781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=61781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}