{"id":14527,"date":"2018-08-27T22:04:26","date_gmt":"2018-08-28T01:04:26","guid":{"rendered":"http:\/\/vocesparalelas.com.ar\/sitio\/?p=14527"},"modified":"2018-08-27T22:08:37","modified_gmt":"2018-08-28T01:08:37","slug":"la-replica-de-la-bandera-del-ejercito-de-los-andes-distingue-al-grupo-de-montana-arq-aldo-araya","status":"publish","type":"post","link":"https:\/\/vocesparalelas.com.ar\/sitio\/la-replica-de-la-bandera-del-ejercito-de-los-andes-distingue-al-grupo-de-montana-arq-aldo-araya\/","title":{"rendered":"La r\u00e9plica de la Bandera del Ej\u00e9rcito de los Andes distingue al Grupo de Monta\u00f1a \u201cArq. Aldo Araya\u201d"},"content":{"rendered":"<p>El Instituto Preuniversitario de la Universidad Nacional de San Juan Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d recibi\u00f3 la r\u00e9plica de la Bandera del Ej\u00e9rcito de los Andes, en el marco del acto en conmemoraci\u00f3n del fallecimiento del Gral. Jos\u00e9 de San Mart\u00edn.<\/p>\n<p>El Ministerio de Educaci\u00f3n de la Naci\u00f3n dispuso en el a\u00f1o 1981 otorgar a los establecimientos educativos de nivel medio que hayan cumplido el centenario de su fundaci\u00f3n una r\u00e9plica de la Bandera y por poseer el Grupo de Monta\u00f1a \u201cArq. Aldo Araya\u201d, de la Instituci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14533\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-07.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-07.jpg 1000w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-07-300x200.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-07-768x512.jpg 768w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-07-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Es importante recordar que la Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d fue fundada en diciembre de 1871, recibi\u00f3 el emblema patrio para contribuir al resguardo del acervo nacional y por aportar a la formaci\u00f3n de ciudadanos con el Grupo de Monta\u00f1a.<\/p>\n<p>La Bandera recibida y sus atributos, al igual que la Banderola del Gran Capit\u00e1n, fueron bendecidos y entregados a los correspondientes estudiantes que portan la Ense\u00f1a Patria.<\/p>\n<p>Participaron del acto el rector de la UNSJ, Dr. Oscar Nasisi; la vicerrectora Esp. M\u00f3nica Coca; el director de la Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d, Ing. Jorge Guti\u00e9rrez; el comandante de la 8\u00aa Brigada de Monta\u00f1a, Cnel. Alberto Qui\u00f1ones; dem\u00e1s autoridades universitarias; directivos de los colegios preuniversitarios; docentes; personal nodocente y alumnos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14532\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-05.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-05.jpg 1000w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-05-300x200.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-05-768x512.jpg 768w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-05-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>El acto se inici\u00f3 con la entrada de la Bandera Argentina y luego se enton\u00f3 el Himno Nacional Argentino al comp\u00e1s de la Banda de M\u00fasica \u201cCnel. Juan Manuel Cabot\u201d, quienes estuvieron con el uniforme de la \u00e9poca.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14534\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-08.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-08.jpg 1000w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-08-300x200.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-08-768x512.jpg 768w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/eidfs-bandera-08-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/lfwXXKiXUiY?start=3&#038;feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>Posteriormente, se enton\u00f3 el Himno al Gral. Jos\u00e9 de San Mart\u00edn.<\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/6oS1eVRds7s?start=11&#038;feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>El Prof. Daniel Arias, fue el responsable de resaltar los valores del Gral. Jos\u00e9 de San Mart\u00edn.<\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/mNXt3XO9eMU?start=9&#038;feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>Seguidamente, el sacerdote de la Parroquia de La Merced hizo la bendici\u00f3n de la bandera del Ej\u00e9rcito de Los Andes y de la Banderola del Gran Capit\u00e1n.<\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/HHc8fDf147w?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>A continuaci\u00f3n, las locutoras leyeron la Resoluci\u00f3n de la Escuela Industrial Domingo Faustino Sarmiento.<\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/uxweAZX4R4w?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>Fue entonces el momento m\u00e1s emotivo cuando se entreg\u00f3 la Bandera del Ej\u00e9rcito de Los Andes a sus respectivos alumnos del Grupo de Monta\u00f1a de la Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d, por parte del director de la Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d, Ing. Jorge Guti\u00e9rrez; el comandante de la 8\u00aa Brigada de Monta\u00f1a, Cnel. Alberto Qui\u00f1ones.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14528\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFSS-BANDERA-01.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFSS-BANDERA-01.jpg 1000w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFSS-BANDERA-01-300x200.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFSS-BANDERA-01-768x512.jpg 768w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFSS-BANDERA-01-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<ul>\n<li>Abanderado Mariano Mart\u00ednez<\/li>\n<li>1\u00ba Escolta Santiago Garc\u00e9s<\/li>\n<li>2\u00ba Escolta Emilia Gazali<\/li>\n<\/ul>\n<p>La cual se realice el cambio de abanderado el 17 de Agosto, fecha del Fallecimiento del Gral. Jos\u00e9 de San Mart\u00edn<\/p>\n<p>Para finalizar este emotivo acto fuel Rector de la UNSJ, Dr. Oscar Nasisi iz\u00f3 la Banderola del Gran Capit\u00e1n acompa\u00f1ado por el director de la Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d, Ing. Jorge Guti\u00e9rrez y el comandante de la 8\u00aa Brigada de Monta\u00f1a, Cnel. Alberto Qui\u00f1ones.<\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/2P81Ozt9qes?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>Seguidamente, el comandante de la 8\u00aa Brigada de Monta\u00f1a, Cnel. Alberto Qui\u00f1ones, quien destac\u00f3 la importancia de la Bandera del Ej\u00e9rcito de Los Andes que otorga el Ej\u00e9rcito Argentino al Grupo de Monta\u00f1a de la Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d de la UNSJ.<\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/M_MmunhNBn8?start=15&#038;feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>Para cerrar el acto, las autoridades entregaron el c\u00f3ndor de otro a los integrantes del grupo de monta\u00f1a de la Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d, que se destacaron en su trabajo con los grandes valores de compa\u00f1erismo, respeto y amor a la Patria Argentina.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14530\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-03.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-03.jpg 1000w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-03-300x200.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-03-768x512.jpg 768w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-03-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14529\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-01.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-01.jpg 1000w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-01-300x200.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-01-768x512.jpg 768w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/08\/EIDFS-BANDERA-01-800x534.jpg 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Preuniversitario de la Universidad Nacional de San Juan Escuela Industrial \u201cDomingo Faustino Sarmiento\u201d recibi\u00f3 la r\u00e9plica de la<\/p>\n","protected":false},"author":3,"featured_media":14531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1,7],"tags":[],"class_list":["post-14527","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-videos","post_format-post-format-video"],"acf":[],"_links":{"self":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/14527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=14527"}],"version-history":[{"count":0,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/14527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media\/14531"}],"wp:attachment":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=14527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=14527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=14527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}