{"id":13273,"date":"2018-07-06T23:17:20","date_gmt":"2018-07-07T02:17:20","guid":{"rendered":"http:\/\/vocesparalelas.com.ar\/sitio\/?p=13273"},"modified":"2018-07-07T00:31:38","modified_gmt":"2018-07-07T03:31:38","slug":"la-comunidad-cientifica-mundial-evalua-las-condiciones-de-veladero-para-estudiar-el-eclipse-de-sol-en-2019","status":"publish","type":"post","link":"https:\/\/vocesparalelas.com.ar\/sitio\/la-comunidad-cientifica-mundial-evalua-las-condiciones-de-veladero-para-estudiar-el-eclipse-de-sol-en-2019\/","title":{"rendered":"La comunidad cient\u00edfica mundial eval\u00faa las condiciones de Veladero para estudiar el eclipse de Sol en 2019"},"content":{"rendered":"<p>Veladero recibi\u00f3, a trav\u00e9s de su programa Mina Abierta, al cient\u00edfico franc\u00e9s y reconocido especialista en eclipses y miembro de la International Astronomical Union (IAU), Xavier Jubier, quien evalu\u00f3 las condiciones del sitio donde est\u00e1 emplazada la mina y que permitir\u00eda apreciar y estudiar en detalle el eclipse de Sol que ocurrir\u00e1 el 2 de julio de 2019.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13277\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/ECLIPSE-DE-SOL.jpg\" alt=\"\" width=\"738\" height=\"491\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/ECLIPSE-DE-SOL.jpg 640w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/ECLIPSE-DE-SOL-300x200.jpg 300w\" sizes=\"auto, (max-width: 738px) 100vw, 738px\" \/><\/p>\n<p>Esta visita est\u00e1 en sinton\u00eda con la evaluaci\u00f3n que est\u00e1n haciendo cient\u00edficos locales, quienes aseguran que San Juan, en especial el departamento Iglesia, es uno de los sitios privilegiados para observar este fen\u00f3meno, por lo que se espera una fuerte convocatoria tur\u00edstica y cient\u00edfica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13274\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-foto1.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-foto1.jpg 1024w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-foto1-300x169.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-foto1-768x432.jpg 768w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-foto1-800x450.jpg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Durante su visita a la mina, Jubier concluy\u00f3 que Veladero, por su altura, su infraestructura y sus condiciones clim\u00e1ticas, ser\u00e1 un punto ideal desde donde estudiar este fen\u00f3meno astron\u00f3mico.<\/p>\n<p><iframe loading=\"lazy\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/wiMvIfjlZcA?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>\u201cVeladero tiene una gran ubicaci\u00f3n para ver el eclipse por su ubicaci\u00f3n y buen clima. Desde aqu\u00ed se podr\u00e1n ver varios fen\u00f3menos bien espec\u00edficos\u201d, destac\u00f3 el experto, quien cuenta con una reconocida trayectoria internacional en materia astron\u00f3mica. Adem\u00e1s, es el creador del mapa de eclipses solares y lunares de Google.<\/p>\n<p>El eclipse total de Sol comenzar\u00e1 el 2 de julio de 2019 por la ma\u00f1ana al este de Nueva Zelanda, en el Oc\u00e9ano Pac\u00edfico sur, y se mover\u00e1 en direcci\u00f3n noreste para luego virar hacia el sudeste y, al atardecer tocar tierra en Am\u00e9rica del Sur y finalizar a la altura del R\u00edo de la Plata.<\/p>\n<p>\u201cEsto suceder\u00e1 por \u00fanica vez en la vida de aquellos que viven en estas zonas, por lo que es un evento que no deber\u00edan perderse y espero que ese d\u00eda todos puedan mirar al sol\u201d, agreg\u00f3 Xavier.<\/p>\n<p>Vale destacar que el experto resalt\u00f3 la importancia de este fen\u00f3meno que no volver\u00e1 a ocurrir en esta zona de la Tierra hasta dentro de 500 a\u00f1os.<\/p>\n<p>Dado que Veladero est\u00e1 situado sobre lo que ser\u00e1 el borde norte de visibilidad del eclipse, la intenci\u00f3n de Jubier y su equipo de expertos ser\u00e1 obtener, el a\u00f1o pr\u00f3ximo, el mejor punto para tomar mediciones de la geograf\u00eda lunar y la corona solar, entre otras cosas.<\/p>\n<p>\u201cCreo que luego de la visita se confirma que tenemos una gran oportunidad de abrir Veladero a la comunidad cient\u00edfica el a\u00f1o pr\u00f3ximo. La visita de Jubier fue excelente y \u00e9l pudo confirmar el valor de nuestra ubicaci\u00f3n para estudiar el eclipse. Adem\u00e1s, creo que fue muy positivo la charla que comparti\u00f3 con todos nuestros trabajadores\u201d, cont\u00f3 Laura Hern\u00e1ndez, a cargo del programa Mina Abierta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13276\" src=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-Foto3.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-Foto3.jpg 1024w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-Foto3-300x169.jpg 300w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-Foto3-768x432.jpg 768w, https:\/\/vocesparalelas.com.ar\/sitio\/wp-content\/uploads\/2018\/07\/SOL-Foto3-800x450.jpg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veladero recibi\u00f3, a trav\u00e9s de su programa Mina Abierta, al cient\u00edfico franc\u00e9s y reconocido especialista en eclipses y miembro de<\/p>\n","protected":false},"author":3,"featured_media":13275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1,7],"tags":[],"class_list":["post-13273","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-videos","post_format-post-format-video"],"acf":[],"_links":{"self":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/13273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=13273"}],"version-history":[{"count":0,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/13273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media\/13275"}],"wp:attachment":[{"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=13273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=13273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesparalelas.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=13273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}